{"id":845,"date":"2021-07-11T21:33:21","date_gmt":"2021-07-11T20:33:21","guid":{"rendered":"https:\/\/beta.mgemmen.ch\/?post_type=te_announcements&#038;p=845"},"modified":"2021-07-11T21:36:08","modified_gmt":"2021-07-11T20:36:08","slug":"erster-praesident-und-dirigent","status":"publish","type":"te_announcements","link":"https:\/\/www.mgemmen.ch\/index.php\/announcement\/erster-praesident-und-dirigent\/","title":{"rendered":"1880: Erster Pr\u00e4sident und Dirigent"},"content":{"rendered":"<p>Melchior Brunner war der erste Pr\u00e4sident der MGE (1880-1885). Xaver Brunner, Gemeindepr\u00e4sident, pr\u00e4sidierte den Verein 22 Jahre und wurde f\u00fcr seine Verdienste zum Ehrenpr\u00e4sidenten ernannt. Bis ins Jubil\u00e4umsjahr 1980 folgten 19 weitere Pr\u00e4sidenten. Einige davon, vor allem aus der k\u00fcrzeren Vergangenheit, seien hier noch erw\u00e4hnt: Kaspar M\u00fcller, Pietro Nosetti, Alfred Jost, Hermann K\u00fcndig und Stefan Lehner. Im Jubil\u00e4umsjahr 1980 pr\u00e4sidierte Heinrich H\u00e4fliger den Verein.<\/p>\n<p>1880 stellte sich als ersten Dirigent J. L\u00f6tscher aus Doppleschwand zur Verf\u00fcgung. Er amtete damals als Organist in Emmen. Seine Nachfolge trat 1893 Schulinspektor Eberli an. Danach folgten die Dirigenten Franz Josef Steger, Kapellmeister Thomas aus Luzern und Franz Genhard. Zwei wohlverdiente Dirigenten seinen an dieser Stelle erw\u00e4hnt: Hans Ritzmann dirigierte die MGE w\u00e4hrend 32 Jahren (1919-1951) und Darvino Marchesi von 1952-1973 w\u00e4hrend 21 Jahren. Unter seiner Leitung erlebte die MGE ihre H\u00f6chstform. Nach seinem Tod \u00fcbernahm der Vizedirektor das Zepter bis zur Wahl von Hans K\u00e4nzig im Jahre 1973. Peter Kn\u00fcsel wurde 1975 zum Direktor gew\u00e4hlt und dirigierte den Verein auch im Jubil\u00e4umsjahr 1980.<\/p>\n","protected":false},"parent":0,"template":"","class_list":["post-845","te_announcements","type-te_announcements","status-publish","hentry","entry"],"announcement_date":"Announcement Date: Januar 1, 1890","announcement_image":{"iframe":false,"url":"https:\/\/beta.mgemmen.ch\/wp-content\/uploads\/2021\/07\/Xaver_Brunner.jpg"},"_links":{"self":[{"href":"https:\/\/www.mgemmen.ch\/index.php\/wp-json\/wp\/v2\/announcement\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mgemmen.ch\/index.php\/wp-json\/wp\/v2\/announcement"}],"about":[{"href":"https:\/\/www.mgemmen.ch\/index.php\/wp-json\/wp\/v2\/types\/te_announcements"}],"wp:attachment":[{"href":"https:\/\/www.mgemmen.ch\/index.php\/wp-json\/wp\/v2\/media?parent=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}